{"id":37366,"date":"2026-02-05T13:08:56","date_gmt":"2026-02-05T12:08:56","guid":{"rendered":"https:\/\/siciliadascoprire.it\/?post_type=product&#038;p=37366"},"modified":"2026-02-23T16:29:50","modified_gmt":"2026-02-23T15:29:50","slug":"pic-nic-cantina-gorghi-tondi","status":"publish","type":"product","link":"https:\/\/siciliadascoprire.it\/de\/prodotto\/pic-nic-cantina-gorghi-tondi\/","title":{"rendered":"Pic nic in cantina Gorghi Tondi a Mazara del Vallo"},"content":{"rendered":"<h1>Pic Nic in cantina a Mazara del Vallo \u2013 Tenuta Gorghi Tondi<\/h1>\n<h2>Strada del Vino di Marsala \u2013 Terre d\u2019Occidente<\/h2>\n<p>Questa esperienza rientra nel circuito della Strada del Vino di Marsala \u2013 Terre d\u2019Occidente,<br \/>\nil progetto di valorizzazione territoriale che racconta Marsala attraverso cantine, paesaggio, storia e cultura.<\/p>\n<h2>Informazioni chiave<\/h2>\n<ul>\n<li><strong>Luogo:<\/strong> Tenuta Gorghi Tondi \u2013 Mazara del Vallo<\/li>\n<li><strong>Tipologia di esperienza:<\/strong> Pic-nic in cantina con degustazione autonoma<\/li>\n<li><strong>Durata:<\/strong> 1 ora e 30 minuti<\/li>\n<li><strong>Adatta a:<\/strong> Coppie, gruppi, famiglie, wine lovers, over 50<\/li>\n<li><strong>Periodo consigliato:<\/strong> Tutto l\u2019anno<\/li>\n<\/ul>\n<h2>Descrizione dell\u2019esperienza<\/h2>\n<p>Un Pic Nic in cantina a Mazara del Vallo \u2013 Tenuta Gorghi Tondi, con cestino e coperta, per vivere appieno un\u2019esperienza nella natura sicliana.<br \/>\nUna degustazione in autonomia per assaporare i nostri vini con vista sui luoghi in cui nascono, crescono e vengono prodotti,<br \/>\ne per toccare con mano l\u2019esperienza Gorghi Tondi.<\/p>\n<p>L\u2019esperienza si svolge all\u2019interno della pineta con vista sulla riserva naturale Lago Preola e Gorghi Tondi,<br \/>\nun contesto paesaggistico di grande valore ambientale.<br \/>\nLa visita permette di approfondire il legame tra suolo, viticoltura biologica e paesaggio,<br \/>\ncon particolare attenzione allo studio continuo del vitigno Grillo.<\/p>\n<p>Il percorso include anche la visita in cantina e in barricaia, offrendo una visione completa del processo produttivo<br \/>\nprima di vivere il momento pi\u00f9 rilassante: il pic-nic tra i vigneti e la natura incontaminata.<\/p>\n<h2>Perch\u00e9 \u00e8 coerente con la Strada del Vino di Marsala<\/h2>\n<p>Questa esperienza esprime pienamente il legame tra vino, paesaggio e biodiversit\u00e0, valorizzando una viticoltura biologica immersa in un\u2019area naturale protetta. Il pic-nic in tenuta consente di vivere il territorio con lentezza e consapevolezza, in linea con la filosofia della Strada del Vino di Marsala \u2013 Terre d\u2019Occidente.<\/p>","protected":false},"excerpt":{"rendered":"<p>Pic Nic in cantina a Mazara del Vallo \u2013 Tenuta Gorghi Tondi Strada del Vino di Marsala \u2013 Terre d\u2019Occidente Questa esperienza rientra nel circuito della Strada del Vino di Marsala \u2013 Terre d\u2019Occidente, il progetto di valorizzazione territoriale che racconta Marsala attraverso cantine, paesaggio, storia e cultura. Informazioni chiave Luogo: Tenuta Gorghi Tondi \u2013 [&#8230;]\n","protected":false},"featured_media":37372,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"iawp_total_views":12},"product_brand":[],"product_cat":[4937],"product_tag":[],"attrazioni":[],"destinazioni":[4746],"durata_tour":[4827],"fornitore":[],"luogo-di-partenza":[4837],"adatto_a":[4853,4852,4851],"mese_di_partenza":[4857,4865,4864,4863,4862,4861,4860,4859,4858,4856,4855,4854],"class_list":["post-37366","product","type-product","status-publish","has-post-thumbnail","product_cat-strada-del-vino-marsala","destinazioni-mazara-del-vallo","durata_tour-0-3-ore","luogo-di-partenza-marsala","adatto_a-famiglie-con-bambini","adatto_a-coppie","adatto_a-single","mese_di_partenza-aprile","mese_di_partenza-dicembre","mese_di_partenza-novembre","mese_di_partenza-ottobre","mese_di_partenza-settembre","mese_di_partenza-agosto","mese_di_partenza-luglio","mese_di_partenza-giugno","mese_di_partenza-maggio","mese_di_partenza-marzo","mese_di_partenza-febbraio","mese_di_partenza-gennaio","first","instock","virtual","sold-individually","taxable","purchasable","product-type-booking"],"booking_location":"","booking_location_type":"","booking_duration":90,"booking_duration_unit":"minute","booking_buffer":0,"booking_cost":0,"booking_resources":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pic nic in cantina Gorghi Tondi a Mazara del Vallo | Sicilia da scoprire<\/title>\n<meta name=\"description\" content=\"Pic nic in cantina Gorghi Tondi a Mazara del Vallo: esperienza nella natura con degustazione autonoma, visita in pineta, cantina e vini biologici.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/siciliadascoprire.it\/de\/produkt\/pic-nic-cantina-gorghi-tondi\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pic nic in cantina Gorghi Tondi a Mazara del Vallo | Sicilia da scoprire\" \/>\n<meta property=\"og:description\" content=\"Pic nic in cantina Gorghi Tondi a Mazara del Vallo: esperienza nella natura con degustazione autonoma, visita in pineta, cantina e vini biologici.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/siciliadascoprire.it\/de\/produkt\/pic-nic-cantina-gorghi-tondi\/\" \/>\n<meta property=\"og:site_name\" content=\"Sicilia da scoprire\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-23T15:29:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/siciliadascoprire.it\/wp-content\/uploads\/2026\/02\/GORGHI-TONDI-18_07_246-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/siciliadascoprire.it\\\/prodotto\\\/pic-nic-cantina-gorghi-tondi\\\/\",\"url\":\"https:\\\/\\\/siciliadascoprire.it\\\/prodotto\\\/pic-nic-cantina-gorghi-tondi\\\/\",\"name\":\"Pic nic in cantina Gorghi Tondi a Mazara del Vallo | Sicilia da scoprire\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/siciliadascoprire.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/siciliadascoprire.it\\\/prodotto\\\/pic-nic-cantina-gorghi-tondi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/siciliadascoprire.it\\\/prodotto\\\/pic-nic-cantina-gorghi-tondi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/siciliadascoprire.it\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/GORGHI-TONDI-18_07_246-scaled.jpg\",\"datePublished\":\"2026-02-05T12:08:56+00:00\",\"dateModified\":\"2026-02-23T15:29:50+00:00\",\"description\":\"Pic nic in cantina Gorghi Tondi a Mazara del Vallo: esperienza nella natura con degustazione autonoma, visita in pineta, cantina e vini biologici.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/siciliadascoprire.it\\\/prodotto\\\/pic-nic-cantina-gorghi-tondi\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/siciliadascoprire.it\\\/prodotto\\\/pic-nic-cantina-gorghi-tondi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/siciliadascoprire.it\\\/prodotto\\\/pic-nic-cantina-gorghi-tondi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/siciliadascoprire.it\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/GORGHI-TONDI-18_07_246-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/siciliadascoprire.it\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/GORGHI-TONDI-18_07_246-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/siciliadascoprire.it\\\/prodotto\\\/pic-nic-cantina-gorghi-tondi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/siciliadascoprire.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/siciliadascoprire.it\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Pic nic in cantina Gorghi Tondi a Mazara del Vallo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/siciliadascoprire.it\\\/#website\",\"url\":\"https:\\\/\\\/siciliadascoprire.it\\\/\",\"name\":\"Sicilia da Scoprire\",\"description\":\"Tour e viaggi in Sicilia\",\"publisher\":{\"@id\":\"https:\\\/\\\/siciliadascoprire.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/siciliadascoprire.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/siciliadascoprire.it\\\/#organization\",\"name\":\"Sicilia da scoprire\",\"url\":\"https:\\\/\\\/siciliadascoprire.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/siciliadascoprire.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/siciliadascoprire.it\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Logo-Sicilia-da-Scoprire.png\",\"contentUrl\":\"https:\\\/\\\/siciliadascoprire.it\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Logo-Sicilia-da-Scoprire.png\",\"width\":1080,\"height\":1080,\"caption\":\"Sicilia da scoprire\"},\"image\":{\"@id\":\"https:\\\/\\\/siciliadascoprire.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pic nic in cantina Gorghi Tondi a Mazara del Vallo | Sicilia da scoprire","description":"Pic nic in cantina Gorghi Tondi a Mazara del Vallo: esperienza nella natura con degustazione autonoma, visita in pineta, cantina e vini biologici.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/siciliadascoprire.it\/de\/produkt\/pic-nic-cantina-gorghi-tondi\/","og_locale":"de_DE","og_type":"article","og_title":"Pic nic in cantina Gorghi Tondi a Mazara del Vallo | Sicilia da scoprire","og_description":"Pic nic in cantina Gorghi Tondi a Mazara del Vallo: esperienza nella natura con degustazione autonoma, visita in pineta, cantina e vini biologici.","og_url":"https:\/\/siciliadascoprire.it\/de\/produkt\/pic-nic-cantina-gorghi-tondi\/","og_site_name":"Sicilia da scoprire","article_modified_time":"2026-02-23T15:29:50+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/siciliadascoprire.it\/wp-content\/uploads\/2026\/02\/GORGHI-TONDI-18_07_246-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/siciliadascoprire.it\/prodotto\/pic-nic-cantina-gorghi-tondi\/","url":"https:\/\/siciliadascoprire.it\/prodotto\/pic-nic-cantina-gorghi-tondi\/","name":"Pic nic in cantina Gorghi Tondi a Mazara del Vallo | Sicilia da scoprire","isPartOf":{"@id":"https:\/\/siciliadascoprire.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/siciliadascoprire.it\/prodotto\/pic-nic-cantina-gorghi-tondi\/#primaryimage"},"image":{"@id":"https:\/\/siciliadascoprire.it\/prodotto\/pic-nic-cantina-gorghi-tondi\/#primaryimage"},"thumbnailUrl":"https:\/\/siciliadascoprire.it\/wp-content\/uploads\/2026\/02\/GORGHI-TONDI-18_07_246-scaled.jpg","datePublished":"2026-02-05T12:08:56+00:00","dateModified":"2026-02-23T15:29:50+00:00","description":"Pic nic in cantina Gorghi Tondi a Mazara del Vallo: esperienza nella natura con degustazione autonoma, visita in pineta, cantina e vini biologici.","breadcrumb":{"@id":"https:\/\/siciliadascoprire.it\/prodotto\/pic-nic-cantina-gorghi-tondi\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/siciliadascoprire.it\/prodotto\/pic-nic-cantina-gorghi-tondi\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/siciliadascoprire.it\/prodotto\/pic-nic-cantina-gorghi-tondi\/#primaryimage","url":"https:\/\/siciliadascoprire.it\/wp-content\/uploads\/2026\/02\/GORGHI-TONDI-18_07_246-scaled.jpg","contentUrl":"https:\/\/siciliadascoprire.it\/wp-content\/uploads\/2026\/02\/GORGHI-TONDI-18_07_246-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/siciliadascoprire.it\/prodotto\/pic-nic-cantina-gorghi-tondi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/siciliadascoprire.it\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/siciliadascoprire.it\/shop\/"},{"@type":"ListItem","position":3,"name":"Pic nic in cantina Gorghi Tondi a Mazara del Vallo"}]},{"@type":"WebSite","@id":"https:\/\/siciliadascoprire.it\/#website","url":"https:\/\/siciliadascoprire.it\/","name":"Sicilia da Scoprire","description":"Tour e viaggi in Sicilia","publisher":{"@id":"https:\/\/siciliadascoprire.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/siciliadascoprire.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/siciliadascoprire.it\/#organization","name":"Sicilia da scoprire","url":"https:\/\/siciliadascoprire.it\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/siciliadascoprire.it\/#\/schema\/logo\/image\/","url":"https:\/\/siciliadascoprire.it\/wp-content\/uploads\/2022\/12\/Logo-Sicilia-da-Scoprire.png","contentUrl":"https:\/\/siciliadascoprire.it\/wp-content\/uploads\/2022\/12\/Logo-Sicilia-da-Scoprire.png","width":1080,"height":1080,"caption":"Sicilia da scoprire"},"image":{"@id":"https:\/\/siciliadascoprire.it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/siciliadascoprire.it\/de\/wp-json\/wp\/v2\/product\/37366","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/siciliadascoprire.it\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/siciliadascoprire.it\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/siciliadascoprire.it\/de\/wp-json\/wp\/v2\/comments?post=37366"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/siciliadascoprire.it\/de\/wp-json\/wp\/v2\/media\/37372"}],"wp:attachment":[{"href":"https:\/\/siciliadascoprire.it\/de\/wp-json\/wp\/v2\/media?parent=37366"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/siciliadascoprire.it\/de\/wp-json\/wp\/v2\/product_brand?post=37366"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/siciliadascoprire.it\/de\/wp-json\/wp\/v2\/product_cat?post=37366"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/siciliadascoprire.it\/de\/wp-json\/wp\/v2\/product_tag?post=37366"},{"taxonomy":"attrazioni","embeddable":true,"href":"https:\/\/siciliadascoprire.it\/de\/wp-json\/wp\/v2\/attrazioni?post=37366"},{"taxonomy":"destinazioni","embeddable":true,"href":"https:\/\/siciliadascoprire.it\/de\/wp-json\/wp\/v2\/destinazioni?post=37366"},{"taxonomy":"durata_tour","embeddable":true,"href":"https:\/\/siciliadascoprire.it\/de\/wp-json\/wp\/v2\/durata_tour?post=37366"},{"taxonomy":"fornitore","embeddable":true,"href":"https:\/\/siciliadascoprire.it\/de\/wp-json\/wp\/v2\/fornitore?post=37366"},{"taxonomy":"luogo-di-partenza","embeddable":true,"href":"https:\/\/siciliadascoprire.it\/de\/wp-json\/wp\/v2\/luogo-di-partenza?post=37366"},{"taxonomy":"adatto_a","embeddable":true,"href":"https:\/\/siciliadascoprire.it\/de\/wp-json\/wp\/v2\/adatto_a?post=37366"},{"taxonomy":"mese_di_partenza","embeddable":true,"href":"https:\/\/siciliadascoprire.it\/de\/wp-json\/wp\/v2\/mese_di_partenza?post=37366"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}